{"id":57212,"date":"2019-10-07T20:15:14","date_gmt":"2019-10-07T20:15:14","guid":{"rendered":"http:\/\/malamboradio.com\/web\/?p=57212"},"modified":"2019-10-07T20:15:42","modified_gmt":"2019-10-07T20:15:42","slug":"gobernacion-fortalece-40-microempresas-de-retornados-de-venezuela","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2019\/10\/07\/gobernacion-fortalece-40-microempresas-de-retornados-de-venezuela\/","title":{"rendered":"Gobernaci\u00f3n fortalece 40 microempresas de retornados de Venezuela"},"content":{"rendered":"\n<p>Del cono sur del Atl\u00e1ntico son 25 y de la zona central del departamento son 15, para un total de 40 beneficiados del Programa de Generaci\u00f3n de Ingresos y Fortalecimiento Econ\u00f3mico para Retornados de Venezuela que culminaron un curso de formaci\u00f3n en dise\u00f1o de modas que se complementa con la entrega de una m\u00e1quina de coser industrial para fortalecer las famiempresas.<\/p>\n\n\n\n<p>Durante la primera fase del programa se apoy\u00f3 con maquinaria y formaci\u00f3n a 100 retornados, la capacitaci\u00f3n de estas 40 personas hace parte de la segunda fase que contempla beneficiar a otras 60, con lo que se espera impactar a un total de 200 beneficiarios antes de finalizar el a\u00f1o.<\/p>\n\n\n\n<p>El gobernador del Atl\u00e1ntico, Eduardo Verano de la Rosa, en d\u00edas pasados se refiri\u00f3 a esta iniciativa, al exponer ante congresistas y funcionarios del Gobierno nacional en la Asamblea Departamental detalles de la atenci\u00f3n que brinda su administraci\u00f3n a poblaci\u00f3n venezolana y retornada.<\/p>\n\n\n\n<p>&#8220;Es una opci\u00f3n de crear y fortalecer sus negocios, con formaci\u00f3n y maquinaria les estamos dando el empuj\u00f3n que necesitan para dar el primer paso como microempresarios, que cubran sus necesidades y generen m\u00e1s empleos&#8221;, anot\u00f3 Verano.<\/p>\n\n\n\n<p>El mandatario aprovech\u00f3 para recordar que el Atl\u00e1ntico es el tercer departamento, en el pa\u00eds, que m\u00e1s recibe poblaci\u00f3n proveniente del vecino pa\u00eds de manera diaria, y que la efectividad en ese trabajo ha sido exaltada por los Ministerios y la Presidencia de la Rep\u00fablica.<\/p>\n\n\n\n<p>En este curso, 37 integrantes son mujeres y tres son hombres, residentes de los municipios de Baranoa, Repel\u00f3n, Sabanalarga, Suan, Campo de la Cruz, Manat\u00ed, Santa Luc\u00eda, Candelaria y Luruaco, quienes recibieron entrenamiento intensivo en patronaje, corte y confecci\u00f3n de vestidos de ba\u00f1o y ropa de verano con altos est\u00e1ndares de calidad, como antesala a la entrega de la m\u00e1quina de coser.<\/p>\n\n\n\n<p>El secretario del Interior, Jorge \u00c1vila Pareja, explic\u00f3 que el prop\u00f3sito es crear fuentes de generaci\u00f3n de ingresos que dignifiquen la vida de estas personas en el departamento.<\/p>\n\n\n\n<p>&#8220;Buscamos que para ellos reiniciar una nueva vida, en un nuevo pa\u00eds, no se les torne en una pesadilla, que sepan que no est\u00e1n solos, que el gobierno departamental los apoya y la institucionalidad se preocupa por ellos. Influye en la econom\u00eda, en los estados de \u00e1nimo, y todo al final se Traduce en convivencia pac\u00edfica y buenos \u00edndices de seguridad&#8221;, apunt\u00f3 el secretario \u00c1vila.<\/p>\n\n\n\n<p>La beneficiaria del programa, Mabel Echeverri, dijo sentirse agradecida y bendecida, al ser apoyada como colombiana por la Gobernaci\u00f3n y pide a Dios que guie a los funcionarios que lideran este tipo de iniciativas.<\/p>\n\n\n\n<p>&#8220;Aparte de que nos dan las bases te\u00f3ricas tambi\u00e9n nos dan la m\u00e1quina de coser. Ac\u00e1 uno viene a empezar de cero, sin nada, y esto es un medio para empezar a trabajar y producir&#8221;, afirm\u00f3 la beneficiaria.<\/p>\n\n\n\n<p>Otra colombiana retornada de Venezuela que se beneficia con este programa es Mildred Perozo, quien expres\u00f3 que para ella, lo mejor de esta experiencia ha sido desarrollar su conocimiento para buscar recursos que permitan mejorar su n\u00facleo familiar<\/p>\n\n\n\n<p>&#8220;Mi familia y yo estamos felices porque ya podemos iniciar una empresa y realizar el proyecto como debe ser. Me faltaba aprender sobre confecci\u00f3n de vestidos de ba\u00f1o y ya lo hice, adem\u00e1s de que este oficio nos gusta, queremos tener el mayor conocimiento para producir con calidad y recibir mayor remuneraci\u00f3n por nuestro trabajo&#8221;, agreg\u00f3 la se\u00f1ora Perozo.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" src=\"http:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-1024x682.jpeg\" alt=\"\" data-id=\"57213\" data-link=\"http:\/\/malamboradio.com\/web\/?attachment_id=57213\" class=\"wp-image-57213\" srcset=\"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-1024x682.jpeg 1024w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-300x200.jpeg 300w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-768x512.jpeg 768w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-580x387.jpeg 580w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-860x573.jpeg 860w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1-1160x773.jpeg 1160w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" src=\"http:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1024x682.jpeg\" alt=\"\" data-id=\"57214\" data-link=\"http:\/\/malamboradio.com\/web\/?attachment_id=57214\" class=\"wp-image-57214\" srcset=\"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1024x682.jpeg 1024w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-300x200.jpeg 300w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-768x512.jpeg 768w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-580x387.jpeg 580w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-860x573.jpeg 860w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41-1160x773.jpeg 1160w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" src=\"http:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-1024x682.jpeg\" alt=\"\" data-id=\"57215\" data-link=\"http:\/\/malamboradio.com\/web\/?attachment_id=57215\" class=\"wp-image-57215\" srcset=\"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-1024x682.jpeg 1024w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-300x200.jpeg 300w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-768x512.jpeg 768w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-580x387.jpeg 580w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-860x573.jpeg 860w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42-1160x773.jpeg 1160w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.42.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul>\n\n\n\n<p><strong>ASESOR\u00cdA DE COMUNICACIONES<\/strong><br><strong>GOBERNACI\u00d3N DEL ATL\u00c1NTICO<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del cono sur del Atl\u00e1ntico son 25 y de la zona central del departamento son 15, para un total de 40 beneficiados del Programa de Generaci\u00f3n de Ingresos y Fortalecimiento Econ\u00f3mico para Retornados de Venezuela que culminaron un curso de formaci\u00f3n en dise\u00f1o de modas que se complementa con la entrega de una m\u00e1quina de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":57214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-07-at-15.10.41.jpeg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/57212"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=57212"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/57212\/revisions"}],"predecessor-version":[{"id":57216,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/57212\/revisions\/57216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/57214"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=57212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=57212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=57212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}