{"id":226827,"date":"2024-04-17T12:15:47","date_gmt":"2024-04-17T17:15:47","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=226827"},"modified":"2024-04-17T12:15:50","modified_gmt":"2024-04-17T17:15:50","slug":"energumeno-borracho-asesina-a-su-hijo-por-tratar-de-impedir-que-agrediera-a-su-madre","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2024\/04\/17\/energumeno-borracho-asesina-a-su-hijo-por-tratar-de-impedir-que-agrediera-a-su-madre\/","title":{"rendered":"ENERG\u00daMENO BORRACHO ASESINA A SU HIJO POR TRATAR DE IMPEDIR QUE AGREDIERA A SU MADRE."},"content":{"rendered":"\n<p class=\"has-text-align-justify\"><br>Como Hamilton Guerrero Ram\u00edrez, de tan solo 16 a\u00f1os, fue identificado el menor que perdi\u00f3 la vida en manos de su propio padre en un acto de intolerancia y violencia, seg\u00fan reportes policiales de Ataco (Tolima).<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Juan Carlos Guerrero, padre del menor, en avanzado estado de alicoramiento, intent\u00f3 agredir a su esposa al llegar a casa, lo que motiv\u00f3 que su hijo a interviniera en defensa de su madre. Esta acci\u00f3n del menor, encoleriz\u00f3 m\u00e1s al energ\u00fameno agresor que sin pensarlo dos veces desenfundo un arma de fuego y dispar\u00f3 contra su propio hijo.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El menor visiblemente malherido fue trasladado r\u00e1pidamente a un centro asistencial en Aipe, Huila, donde lamentablemente lleg\u00f3 sin signos vitales, seg\u00fan confirm\u00f3 para este medio el coronel Ojeda.<br>Una vez cometido el atroz acto criminal, el padre agresor emprendi\u00f3 la huida con rumbo desconocido, por lo que las autoridades de lugar han emprendido su b\u00fasqueda para que responda ante la justicia por este crimen sin precedentes en la historia del municipio.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Este asesinato determinado por la intolerancia y el abuso del alcohol, ha generado conmoci\u00f3n e indignaci\u00f3n en la comunidad, que clama por justicia. Las investigaciones ya han comenzado en busca de esclarecer los detalles de este lamentable suceso y llevar al responsable a que responda por su acto criminal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como Hamilton Guerrero Ram\u00edrez, de tan solo 16 a\u00f1os, fue identificado el menor que perdi\u00f3 la vida en manos de su propio padre en un acto de intolerancia y violencia, seg\u00fan reportes policiales de Ataco (Tolima). Juan Carlos Guerrero, padre del menor, en avanzado estado de alicoramiento, intent\u00f3 agredir a su esposa al llegar a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":226829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[52,68,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/04\/hamilton-guerrero-homicidio_9902387_20240416203224.png","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/226827"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=226827"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/226827\/revisions"}],"predecessor-version":[{"id":226830,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/226827\/revisions\/226830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/226829"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=226827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=226827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=226827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}