{"id":224261,"date":"2024-02-21T11:21:28","date_gmt":"2024-02-21T16:21:28","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=224261"},"modified":"2024-02-21T11:22:40","modified_gmt":"2024-02-21T16:22:40","slug":"la-fiscal-angelica-monsalve-es-llamada-a-juicio-por-la-fiscalia-general-de-la-nacion","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2024\/02\/21\/la-fiscal-angelica-monsalve-es-llamada-a-juicio-por-la-fiscalia-general-de-la-nacion\/","title":{"rendered":"LA FISCAL ANG\u00c9LICA MONSALVE ES LLAMADA A JUICIO POR LA FISCAL\u00cdA GENERAL DE LA NACION."},"content":{"rendered":"\n<p class=\"has-text-align-justify\"><br>Hoy,  mi\u00e9rcoles, 21 de febrero, la Fiscal\u00eda General de la Naci\u00f3n radic\u00f3 escrito de acusaci\u00f3n en contra de la fiscal Ang\u00e9lica Mar\u00eda Monsalve Gaviria, como presunta responsable del delito de concusi\u00f3n.  <\/p>\n\n\n\n<p class=\"has-text-align-justify\">La cuestionada funcionaria est\u00e1 siendo  procesada por que presuntamente solicit\u00f3 dinero en una investigaci\u00f3n que estaba a su cargo. <br>Seg\u00fan la acusaci\u00f3n de  la Fiscal\u00eda, la funcionaria judicial,  est\u00e1 siendo  procesada por  su negativa reiterada   a comparecer a las citaciones, para aclarar su responsabilidad en la acusacion de solicitar  a trav\u00e9s de un tercero, 600 millones de pesos para archivar una indagaci\u00f3n contra Mart\u00edn Ricardo Manjarr\u00e9s, uno de los procesados por el carrusel de carros blindados de la Unidad Nacional de Protecci\u00f3n (UNP). <\/p>\n\n\n\n<p class=\"has-text-align-justify\">La fiscal Monsalve, presuntamente, era consciente de que el supuesto enviado se presentaba a su nombre y se reuni\u00f3 con la v\u00edctima en, por lo menos, cuatro oportunidad y en los encuentros pidi\u00f3 el dinero a cambio de no ser imputado y evitar que su compa\u00f1era sentimental, Marcela Montes, tambi\u00e9n fuera judicializada. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Se espera que la judicatura se\u00f1ale la fecha para  que la acusaci\u00f3n en contra de la funcionaria judicial se formalize .<br>La Fiscal\u00eda Monsalve,   desde el pasado 1 de febrero  fu\u00e9 retirada de investigaci\u00f3n contra Mart\u00edn Manjarr\u00e9s y Marcela Montes. Esta decisi\u00f3n se tom\u00f3 luego de una recusaci\u00f3n presentada por los investigados, quienes buscan acreditarse como v\u00edctimas en el proceso penal que se adelanta contra Monsalve por concusi\u00f3n.<br>Tras la acusaci\u00f3n y llamado a juicio, Ang\u00e9lica Monsalve manifest\u00f3 que Martha Mancera, fiscal encargada y a quien tild\u00f3 de \u201cusurpadora\u201d, \u201cest\u00e1 utilizando la instituci\u00f3n como arma de venganza en su contra, por haberla denunciado por colaboraci\u00f3n con el narcotr\u00e1fico\u201d. \u201cAl parecer usted va a tener que volver a la facultad a estudiar derecho, pues un juez de garant\u00edas, que es constitucional tutel\u00f3 mi derecho al debido proceso, ordenando al juez 61 que conceda el recurso de queja contra la burda contumacia que present\u00f3 su fiscal t\u00edtere Egohon Bri\u00f1ez Moreno\u201d, dijo adem\u00e1s  la fiscal.<br>La fiscal Monsalve tiene pendiente una segunda imputaci\u00f3n por parte de la Fiscal\u00eda por el delito de fraude procesal, sin embargo, la funcionaria ha hecho caso omiso a las audiencias.<br>La Fiscal\u00eda se\u00f1al\u00f3 a Monsalve por ser presuntamente responsable de varias irregularidades que se presentaron mientras se desempe\u00f1\u00f3 como fiscal adscrita a la Unidad de Administraci\u00f3n P\u00fablica de la Seccional Bogot\u00e1. El ente investigador asegur\u00f3 tener pruebas suficientes para procesar a la funcionaria por haber participado en \u201cla alteraci\u00f3n del contenido de varios documentos\u201d, lo que luego habr\u00eda llevado a otros servidores de la Fiscal\u00eda incurrieran  en error.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, mi\u00e9rcoles, 21 de febrero, la Fiscal\u00eda General de la Naci\u00f3n radic\u00f3 escrito de acusaci\u00f3n en contra de la fiscal Ang\u00e9lica Mar\u00eda Monsalve Gaviria, como presunta responsable del delito de concusi\u00f3n. La cuestionada funcionaria est\u00e1 siendo procesada por que presuntamente solicit\u00f3 dinero en una investigaci\u00f3n que estaba a su cargo. Seg\u00fan la acusaci\u00f3n de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":224262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[99,68,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/FISCAL-MONSALVE.jpg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/224261"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=224261"}],"version-history":[{"count":2,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/224261\/revisions"}],"predecessor-version":[{"id":224266,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/224261\/revisions\/224266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/224262"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=224261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=224261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=224261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}