{"id":224127,"date":"2024-02-19T11:37:33","date_gmt":"2024-02-19T16:37:33","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=224127"},"modified":"2024-02-19T11:54:55","modified_gmt":"2024-02-19T16:54:55","slug":"representacion-de-los-kaamash-en-la-audiencia-publica-final-del-plan-de-desarrollo-departamental","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2024\/02\/19\/representacion-de-los-kaamash-en-la-audiencia-publica-final-del-plan-de-desarrollo-departamental\/","title":{"rendered":"REPRESENTACION DE LOS KAAMASH EN LA AUDIENCIA P\u00daBLICA FINAL DEL PLAN DE DESARROLLO DEPARTAMENTAL."},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-768x1024.png\" alt=\"\" class=\"wp-image-224129\" srcset=\"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-768x1024.png 768w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-225x300.png 225w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-1152x1536.png 1152w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-580x773.png 580w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-860x1147.png 860w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9-1160x1547.png 1160w, https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/image-9.png 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-justify\"><br>De nuevo, la tenaz y perseverante adem\u00e1s, gobernadora de los KAAMASH HU KARIBE, Sra. MARIA ELSY CHARRIS HEREIRA la vimos en acci\u00f3n, esta vez entregando propuestas de las comunidades ind\u00edgenas en el plan de desarrollo departamental. Durante la CONVOCATORIA DE AUDIENCIA P\u00daBLICA FINAL PLAN DE DESARROLLO DEPARTAMENTAL 2024-2027 ATL\u00c1NTICO PARA EL MUNDO.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Esta convocatoria firmada por el Gerente de Asuntos \u00c9tnicos de la Gobernaci\u00f3n del Atl\u00e1ntico. Dr. LUIS FERNANDO CASSIANI HERRERA tuvo lugar a las 14:00 horas del viernes 16 de febrero del a\u00f1o en curso, en el piso 12 de la instalaciones de la gobernaci\u00f3n del Atl\u00e1ntico.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Propio de su estilo, la vimos salir sonriente y satisfecha del trabajo presentado en pro de la comunidad \u00e9tnica que deposit\u00f3 en ella la confianza para salir del anonimato que por a\u00f1os les ha impedido visibilizarse y ser tenidos en cuenta para recibir los ben\u00e9ficos a que tienen derecho como grupo \u00e9tnico en minor\u00eda.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Nos dijo estar muy contenta por todas y cada una de las invitaciones que les llegan, y que esto es un gran paso, si tenemos en cuenta que ya no somos desconocidos y que nosotros los KAAMASH HU KARIBE, estamos siendo tenidos en cuenta como etnia, por las autoridades locales, departamentales, nacionales e internacionales.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Seguimos en la lucha, con gran motivaci\u00f3n por los derechos de mi raza, de mi gente, de mi etnia\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nuevo, la tenaz y perseverante adem\u00e1s, gobernadora de los KAAMASH HU KARIBE, Sra. MARIA ELSY CHARRIS HEREIRA la vimos en acci\u00f3n, esta vez entregando propuestas de las comunidades ind\u00edgenas en el plan de desarrollo departamental. Durante la CONVOCATORIA DE AUDIENCIA P\u00daBLICA FINAL PLAN DE DESARROLLO DEPARTAMENTAL 2024-2027 ATL\u00c1NTICO PARA EL MUNDO. Esta convocatoria firmada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":224128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60,56,98],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2024\/02\/indigenas.jpg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/224127"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=224127"}],"version-history":[{"count":2,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/224127\/revisions"}],"predecessor-version":[{"id":224138,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/224127\/revisions\/224138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/224128"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=224127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=224127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=224127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}