{"id":217391,"date":"2023-11-11T12:17:45","date_gmt":"2023-11-11T17:17:45","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=217391"},"modified":"2023-11-11T12:17:47","modified_gmt":"2023-11-11T17:17:47","slug":"lista-la-reforma-tributaria-2024-habra-cambios-en-los-impuestos-de-personas-naturales","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2023\/11\/11\/lista-la-reforma-tributaria-2024-habra-cambios-en-los-impuestos-de-personas-naturales\/","title":{"rendered":"LISTA LA REFORMA TRIBUTARIA 2024.        HABR\u00c1 CAMBIOS EN LOS IMPUESTOS DE PERSONAS NATURALES"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">La aprobada reforma del gobierno Petro, en vigencia desde 2024, traer\u00e1 ajustes en impuestos para personas naturales, afectando la declaraci\u00f3n de renta y el pago de tributos. En medio de las controversias por el incremento del impuesto predial, la atenci\u00f3n se centra en las modificaciones que experimentar\u00e1n las personas naturales el pr\u00f3ximo a\u00f1o con la implementaci\u00f3n de la reforma tributaria.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La reforma, aprobada este a\u00f1o por el Congreso, dirigida por el gobierno Petro, generar\u00e1 varios cambios en impuestos para las personas naturales, incluyendo la declaraci\u00f3n de renta. Seg\u00fan \u00c1ngel Custodio Cabrera, exministro de Trabajo, las normas actuales implicar\u00e1n ajustes en impuestos al patrimonio, dividendos y ganancias ocasionales. La declaraci\u00f3n de renta y el pago de impuestos en 2024 se basar\u00e1n en la informaci\u00f3n del a\u00f1o 2023.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Los contribuyentes laborales enfrentar\u00e1n mayores cargas, ya que no podr\u00e1n deducir m\u00e1s ingresos, limit\u00e1ndose a 790 UVT en lugar de 2880 UVT, seg\u00fan Cabrera. Esto impacta tambi\u00e9n la deducci\u00f3n por pr\u00e9stamos de vivienda o de Icetex, limitada a un m\u00e1ximo de 56 millones. En cuanto a los dividendos, aquellos con rentas de capital o tipos similares ver\u00e1n un aumento en el impuesto, ya que ahora se integran a los ingresos totales.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En el impuesto de ganancias ocasionales, la tarifa aumenta del 10% al 15%, con la posibilidad de disminuir al vender una vivienda para invertir en una nueva, seg\u00fan Cabrera.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La tarifa de patrimonio, actualmente en 1,5%, aplicar\u00e1 hasta el 2026. En 2027, disminuir\u00e1 al 1% para patrimonios que superen las 122,000 UVT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aprobada reforma del gobierno Petro, en vigencia desde 2024, traer\u00e1 ajustes en impuestos para personas naturales, afectando la declaraci\u00f3n de renta y el pago de tributos. En medio de las controversias por el incremento del impuesto predial, la atenci\u00f3n se centra en las modificaciones que experimentar\u00e1n las personas naturales el pr\u00f3ximo a\u00f1o con la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":217394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,76,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2023\/11\/billetes.colombianos-1200x768-1.jpg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/217391"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=217391"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/217391\/revisions"}],"predecessor-version":[{"id":217395,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/217391\/revisions\/217395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/217394"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=217391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=217391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=217391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}