{"id":214790,"date":"2023-10-09T15:50:42","date_gmt":"2023-10-09T20:50:42","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=214790"},"modified":"2023-10-09T15:50:43","modified_gmt":"2023-10-09T20:50:43","slug":"si-israel-contraataca-ejecutaremos-los-rehenes-dice-abu-obeida","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2023\/10\/09\/si-israel-contraataca-ejecutaremos-los-rehenes-dice-abu-obeida\/","title":{"rendered":"SI ISRAEL CONTRAATACA EJECUTAREMOS LOS REHENES DICE ABU OBEIDA"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">&#8220;Cualquier ataque contra casas de inocentes en Gaza sin previo aviso resultar\u00e1 en la ejecuci\u00f3n p\u00fablica de un reh\u00e9n&#8221;, dijo Abu Obeida, portavoz de las brigadas de Al Qasam, brazo armado de Ham\u00e1s. La cuesti\u00f3n de los m\u00e1s de 100 rehenes tomados por Ham\u00e1s en su ataque del s\u00e1bado pasado est\u00e1 dificultando el contraataque de Israel, que se intensific\u00f3 este lunes con bombardeos incesantes sobre Gaza, ya que Ham\u00e1s amenaz\u00f3 con ejecutar a rehenes en represalia por ataques indiscriminados contra la poblaci\u00f3n civil.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Reaccion\u00f3 as\u00ed a la intensificaci\u00f3n de los bombardeos israel\u00edes sobre Gaza durante la jornada de hoy, que destruyeron instalaciones militares de Ham\u00e1s y la Yihad Isl\u00e1mica, pero tambi\u00e9n infraestructura civil y edificios residenciales.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Palestinos de la Franja denunciaron hoy que Israel dej\u00f3 de emplear el m\u00e9todo conocido como &#8220;golpes en tejado&#8221;, por el que se lanzan dispositivos no explosivos a los tejados de las casas como preaviso de que se van a bombardear en unos minutos, para que la poblaci\u00f3n pueda salir, a menudo con el tiempo justo.&#8221;No son ataques normales, van contra civiles. Donde hay casas de civiles, atacan, donde hay ni\u00f1os y mujeres, atacan&#8221;, cont\u00f3 horas antes a EFE Ahmad Tartouri, un gazat\u00ed de 48 a\u00f1os.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En tres d\u00edas de guerra, los bombardeos israel\u00edes en Gaza han dejado ya m\u00e1s de 687 muertos, entre ellos 140 ni\u00f1os y 105 mujeres, y 3726 heridos, seg\u00fan el \u00faltimo recuento de las autoridades gazat\u00edes, que advierten que a\u00fan quedan muchas v\u00edctimas bajo los escombros. Los muertos en Israel superan los 900 y se han contabilizado m\u00e1s de 2.600 heridos por el ataque, una cifra que sigue aumentando al encontrarse cuerpos en el sur del pa\u00eds. A esta n\u00famero se suman m\u00e1s de 100 personas que fueron capturadas por milicianos palestinos y trasladadas a Gaza, seg\u00fan confirm\u00f3 el Gobierno israel\u00ed.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Este lunes, adem\u00e1s, se registraron nuevos intercambios de fuego y enfrentamientos armados en la frontera entre Israel y L\u00edbano. El grupo chi\u00ed liban\u00e9s Hizbul\u00e1 atac\u00f3 con misiles teledirigidos y morteros al menos dos objetivos militares de las fuerzas israel\u00edes, despu\u00e9s de perder a tres miembros en una serie de ataques perpetrados esta tarde por el Estado jud\u00edo contra el sur del L\u00edbano.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Poco antes, dos milicianos de la Yihad Isl\u00e1mica Palestina murieron en un enfrentamiento armado con tropas israel\u00edes tras cruzar la frontera desde L\u00edbano. El ministro de Exteriores israel\u00ed, Eli Cohen, anunci\u00f3 hoy que la guerra durar\u00eda a\u00fan mucho, en todo caso m\u00e1s que &#8220;unos pocos d\u00edas&#8221;, y que el objetivo ser\u00e1 eliminar la capacidad militar de Ham\u00e1s de atacar a civiles.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Mientras las fuerzas armadas bombardean Gaza, contin\u00faan tambi\u00e9n los combates en varias comunidades israel\u00edes cercanas a la Franja, que fueron tomadas el s\u00e1bado en un ataque sorpresa. Unos mil milicianos de Ham\u00e1s se infiltraron de golpe en territorio de Israel, haci\u00e9ndose con el control de m\u00e1s de 30 comunidades, confirm\u00f3 hoy una portavoz de las Fuerzas Armadas israel\u00edes, la comandante Libby Weiss. &#8220;En varias comunidades del sur hay ahora mismo unidades del Ej\u00e9rcito combatiendo a terroristas para recuperar estas comunidades. Los combates est\u00e1n continuando en estos momentos dentro del territorio israel\u00ed&#8221;, subray\u00f3 Weiss.<\/p>\n\n\n\n<p>&#8220;La primera prioridad es restablecer la seguridad en la frontera, de manera que ning\u00fan terrorista quede dentro de territorio israel\u00ed. La segunda, traer de vuelta a los rehenes&#8221;, agreg\u00f3 Weiss, sin entrar en detalles de c\u00f3mo se podr\u00eda conseguir el segundo objetivo. Fuentes conocedoras del asunto han confirmado  que Catar participa en tareas de mediaci\u00f3n con Ham\u00e1s e Israel para tratar un posible intercambio de rehenes, subrayando que se trabaja con &#8220;mucha cautela&#8221; dada la &#8220;extrema sensibilidad&#8221; de la situaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">De momento, tanto Israel como el grupo palestino han negado la existencia de negociaciones en este sentido. &#8220;No estamos negociando con nadie. Estamos en guerra. Queremos hacer segura nuestra frontera&#8221;, dijo Lior Haiat, portavoz del Ministerio de Exteriores israel\u00ed durante una rueda de prensa.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Haiat tampoco quiso dar detalles sobre una posible intervenci\u00f3n terrestre en Gaza y se limit\u00f3 a se\u00f1alar que se trata de &#8220;destruir la infraestructura del terror&#8221;. En el mismo sentido se expres\u00f3 hoy el primer ministro de Israel, Benjam\u00edn Netanyahu, tras comparar &#8220;las atrocidades de Ham\u00e1s&#8221; con las del Estado Isl\u00e1mico y prometiendo &#8220;eliminar&#8221; a Ham\u00e1s &#8220;exactamente de la misma forma que el mundo ilustrado elimin\u00f3 al Estado Isl\u00e1mico&#8221;.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">&#8220;Al final de la campa\u00f1a, todos nuestros enemigos sabr\u00e1n que fue un terrible error atacar a Israel. Lo que se har\u00e1 a nuestros enemigos en los pr\u00f3ximos d\u00edas resonar\u00e1 en ellos durante generaciones&#8221;, dijo Netanyahu. El ministro de Defensa israel\u00ed, Yoav Gallant, orden\u00f3 el bloqueo total de la Franja de Gaza, lo que significa que el enclave palestino quedar\u00e1 sin suministro de electricidad, alimentos y combustible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Cualquier ataque contra casas de inocentes en Gaza sin previo aviso resultar\u00e1 en la ejecuci\u00f3n p\u00fablica de un reh\u00e9n&#8221;, dijo Abu Obeida, portavoz de las brigadas de Al Qasam, brazo armado de Ham\u00e1s. La cuesti\u00f3n de los m\u00e1s de 100 rehenes tomados por Ham\u00e1s en su ataque del s\u00e1bado pasado est\u00e1 dificultando el contraataque de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":214810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[83,70],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2023\/10\/Israel-18_0.jpg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/214790"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=214790"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/214790\/revisions"}],"predecessor-version":[{"id":214811,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/214790\/revisions\/214811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/214810"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=214790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=214790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=214790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}