{"id":191100,"date":"2022-09-19T16:56:37","date_gmt":"2022-09-19T21:56:37","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=191100"},"modified":"2022-09-19T16:56:40","modified_gmt":"2022-09-19T21:56:40","slug":"patrullero-muerto-y-patrullera-herida-es-el-saldo-de-aparatoso-accidente-en-vias-del-magdalena","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2022\/09\/19\/patrullero-muerto-y-patrullera-herida-es-el-saldo-de-aparatoso-accidente-en-vias-del-magdalena\/","title":{"rendered":"PATRULLERO  MUERTO Y PATRULLERA HERIDA ES EL SALDO DE APARATOSO ACCIDENTE EN VIAS DEL MAGDALENA."},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Un tr\u00e1gico siniestro vial se registr\u00f3 alrededor de las 4:00 de la ma\u00f1ana de este lunes en el kil\u00f3metro 13 de la v\u00eda que del corregimiento de Palermo conduce al municipio de Sitionuevo, Magdalena.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Tras el fatal accidente, result\u00f3 muerto un patrullero de la Polic\u00eda, identificado como Roberto Alfonso Su\u00e1rez Leonel, quien era natural de Santa Marta; mientras que la patrullera que lo acompa\u00f1aba result\u00f3 herida, la uniformada fue identificada como Irina Leonor Su\u00e1rez Sinning.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Seg\u00fan el informe de las autoridades, los uniformados se encontraban realizando labores de acompa\u00f1amiento a un precandidato a la Alcald\u00eda de Sitionuevo y al llegar a la direcci\u00f3n antes mencionada, los polic\u00edas redujeron la velocidad porque hab\u00edan varios b\u00fafalos sobre la v\u00eda.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Es en ese instante cuando la camioneta que ven\u00eda detr\u00e1s de la motocicleta de los patrulleros, a la que le hac\u00edan el acompa\u00f1amiento, no alcanz\u00f3 a frenar a tiempo y se llev\u00f3 por delante a los polic\u00edas y a varios de los animales.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Tras lo sucedido, los polic\u00edas fueron auxiliados por los ocupantes de la camioneta en menci\u00f3n y fueron trasladados al hospital local de Sitionuevo, donde los galenos confirmaron el deceso del patrullero Su\u00e1rez Leonel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tr\u00e1gico siniestro vial se registr\u00f3 alrededor de las 4:00 de la ma\u00f1ana de este lunes en el kil\u00f3metro 13 de la v\u00eda que del corregimiento de Palermo conduce al municipio de Sitionuevo, Magdalena. Tras el fatal accidente, result\u00f3 muerto un patrullero de la Polic\u00eda, identificado como Roberto Alfonso Su\u00e1rez Leonel, quien era natural de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":191103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[94,68,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2022\/09\/ACCI-VACA.png","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/191100"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=191100"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/191100\/revisions"}],"predecessor-version":[{"id":191104,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/191100\/revisions\/191104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/191103"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=191100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=191100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=191100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}