{"id":190017,"date":"2022-09-09T13:52:46","date_gmt":"2022-09-09T18:52:46","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=190017"},"modified":"2022-09-09T13:52:48","modified_gmt":"2022-09-09T18:52:48","slug":"ayda-victoria-merlano-en-la-mira-de-la-fiscalia-por-enriquecimiento-ilicito-y-lavado-de-activos","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2022\/09\/09\/ayda-victoria-merlano-en-la-mira-de-la-fiscalia-por-enriquecimiento-ilicito-y-lavado-de-activos\/","title":{"rendered":"AYDA VICTORIA MERLANO EN LA MIRA DE LA FISCAL\u00cdA POR  ENRIQUECIMIENTO ILICITO Y LAVADO DE ACTIVOS ."},"content":{"rendered":"\n<p class=\"has-text-align-justify\">La Fiscal\u00eda abri\u00f3 un proceso por lavado de activos y enriquecimiento il\u00edcito en contra de la \u2018influencer\u2019 Aida Victoria Merlano porque har\u00eda parte de un entramado delictivo que pretend\u00eda ocultar los bienes de su mam\u00e1, la excongresista Aida Merlano, a trav\u00e9s de una sociedad de papel.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Desde hace dos a\u00f1os la Fiscal\u00eda adelanta un proceso de extinci\u00f3n de dominio en contra de los bienes de la pr\u00f3fuga excongresista Aida Merlano. En las pesquisas el ente acusador descubri\u00f3 que desde el 2019 Aida Victoria Merlano aparece como la representante legal de una compa\u00f1\u00eda de ingenier\u00eda, arquitectura y urbanismo denominada ESAID SAS., empresa que figura con un capital de $2.200\u2019000.0000.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Se infiere razonablemente tal y como se comprobar\u00e1 en el ac\u00e1pite de razonamiento probatorio de esta demanda que la Sra. Aida Merlano Rebolledo adquiri\u00f3 estos bienes en el desarrollo de actividades il\u00edcitas, adem\u00e1s, que los mezcl\u00f3 con bienes l\u00edcitos\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En el expediente, la pepa del asunto est\u00e1 en que el ente acusador descubri\u00f3 que varios de los bienes que eran de la excongresista Aida Merlano, \u201ccomenzaron a ser trasladados s\u00fabitamente\u201d en 2019 a la empresa ESAID SAS. Esos bienes se traspasaron bajo la figura de donaci\u00f3n de manera r\u00e1pida y sospechosa.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Otro detalle que detect\u00f3 la Fiscal\u00eda es que al momento del traspaso de esos bienes la empresa ESAID SAS. no exist\u00eda f\u00edsicamente, es decir, era una compa\u00f1\u00eda ficticia.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u201c(\u2026) lo que nos dan a entender que buscaba el ocultamiento de dichos bienes a la vista jur\u00eddica del ente investigador. Lo que configura sin lugar a duda un indicio grave\u201d.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda abri\u00f3 un proceso por lavado de activos y enriquecimiento il\u00edcito en contra de la \u2018influencer\u2019 Aida Victoria Merlano porque har\u00eda parte de un entramado delictivo que pretend\u00eda ocultar los bienes de su mam\u00e1, la excongresista Aida Merlano, a trav\u00e9s de una sociedad de papel. Desde hace dos a\u00f1os la Fiscal\u00eda adelanta un proceso&#8230;<\/p>\n","protected":false},"author":1,"featured_media":190020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[78,68,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2022\/09\/AYDA-VICTORIA.webp","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/190017"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=190017"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/190017\/revisions"}],"predecessor-version":[{"id":190021,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/190017\/revisions\/190021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/190020"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=190017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=190017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=190017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}