{"id":187578,"date":"2022-08-11T16:57:14","date_gmt":"2022-08-11T21:57:14","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=187578"},"modified":"2022-08-11T16:57:17","modified_gmt":"2022-08-11T21:57:17","slug":"presidente-biden-mantiene-ayudas-a-colombia-para-luchar-contra-el-narcotrafico","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2022\/08\/11\/presidente-biden-mantiene-ayudas-a-colombia-para-luchar-contra-el-narcotrafico\/","title":{"rendered":"PRESIDENTE BIDEN MANTIENE AYUDAS A COLOMBIA PARA LUCHAR CONTRA EL NARCOTRAFICO."},"content":{"rendered":"\n<p class=\"has-text-align-justify\">El presidente de Estados Unidos, Joe Biden, emiti\u00f3 este martes una orden en que insta a los departamentos de Estado y de Defensa a seguir prestando ayuda al Gobierno de Colombia en materia de lucha contra el tr\u00e1fico de drogas<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En un memorando, Biden indic\u00f3 que la interdicci\u00f3n de aeronaves razonablemente sospechosas de llevar a cabo operaciones de tr\u00e1fico de drogas en el espacio a\u00e9reo colombiano es &#8220;necesaria&#8221; a causa de la amenaza extraordinaria que el tr\u00e1fico ilegal de drogas representa para la seguridad nacional de Colombia.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Biden tambi\u00e9n apunt\u00f3 que el pa\u00eds caribe\u00f1o tiene los procedimiento apropiados en marcha para protegerse ante la p\u00e9rdida de vidas inocentes en el aire y en tierra en relaci\u00f3n a estas operaciones de interdicci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Estos procedimientos incluyen medios efectivos para identificar y alertar a una aeronave antes de que se use la fuerza contra la misma.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La tendencia de crecimiento de los cultivos de coca en Colombia se fren\u00f3 en 2018 pero el n\u00famero de hect\u00e1reas sembradas sigue en m\u00e1ximos hist\u00f3ricos pese a que pas\u00f3 de 171.000 en 2017 a 154.000 en 2019, seg\u00fan los informes de la Oficina de la ONU contra la Droga y el Delito (Unodc).<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En 2014 una sentencia de la Corte Constitucional colombiana orden\u00f3 la suspensi\u00f3n de las aspersiones a\u00e9reas luego de que la Organizaci\u00f3n Mundial de la Salud (OMS) incluyera al glifosato entre los herbicidas que pueden causar c\u00e1ncer en humanos.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">A mediados de 2015, durante el Gobierno de Juan Manuel Santos, el Consejo Nacional de Estupefacientes (CNE) acat\u00f3 la sentencia del alto tribunal que dos a\u00f1os despu\u00e9s emiti\u00f3 un nuevo fallo en el que estableci\u00f3 que ser\u00eda posible reanudar las aspersiones a\u00e9reas si una investigaci\u00f3n cient\u00edfica, de forma &#8220;objetiva y concluyente, demuestra la ausencia de da\u00f1o para la salud y el medio ambiente&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Joe Biden, emiti\u00f3 este martes una orden en que insta a los departamentos de Estado y de Defensa a seguir prestando ayuda al Gobierno de Colombia en materia de lucha contra el tr\u00e1fico de drogas En un memorando, Biden indic\u00f3 que la interdicci\u00f3n de aeronaves razonablemente sospechosas de llevar a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":187579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[70,86,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2022\/08\/biden_6251114_20220523070042.jpg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/187578"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=187578"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/187578\/revisions"}],"predecessor-version":[{"id":187580,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/187578\/revisions\/187580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/187579"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=187578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=187578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=187578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}