{"id":157447,"date":"2021-06-05T11:44:30","date_gmt":"2021-06-05T11:44:30","guid":{"rendered":"https:\/\/malamboradio.com\/web\/?p=157447"},"modified":"2021-06-05T11:44:35","modified_gmt":"2021-06-05T11:44:35","slug":"barranquilla-agenda-la-cultura-presencial-en-5-parques-diferentes-de-la-ciudad-este-fin-de-semana","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2021\/06\/05\/barranquilla-agenda-la-cultura-presencial-en-5-parques-diferentes-de-la-ciudad-este-fin-de-semana\/","title":{"rendered":"BARRANQUILLA AGENDA LA CULTURA PRESENCIAL EN 5 PARQUES DIFERENTES DE LA CIUDAD ESTE FIN DE SEMANA"},"content":{"rendered":"\n<p><em><strong>Habr\u00e1 un concierto con Los Gaiteros de Pueblo Santo y Lina Babilonia.<\/strong><\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify\">La secretaria de Cultura del Distrito, Mar\u00eda Teresa Fern\u00e1ndez, inform\u00f3 este viernes que est\u00e1 definida la programaci\u00f3n art\u00edstica y cultural que se desarrollar\u00e1 este fin de semana en cinco parques ya determinados, ubicados en las cinco localidades de Barranquilla.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u201cEstamos muy contentos porque este fin de semana tendremos la oportunidad de disfrutar de los talleres de Casa de Cultura, que ven\u00edan realiz\u00e1ndose de manera virtual, los sacaremos a los parques de la ciudad. Tenemos que de 9:00 a 11:00 de la ma\u00f1ana en cinco parques de las cinco localidades del Distrito tendremos actividades de artes esc\u00e9nicas, artes pl\u00e1sticas, t\u00edteres, maquillaje, etc\u00e9tera\u201d, manifest\u00f3 inicialmente Mar\u00eda Teresa Fern\u00e1ndez.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Mar\u00eda Teresa Fern\u00e1ndez agreg\u00f3 que \u201cla invitaci\u00f3n es a que nos acompa\u00f1en, porque esa no ser\u00e1 la \u00fanica actividad que vamos a tener. Hoy s\u00e1bado, desde las 4:00 de la tarde tendremos una presentaci\u00f3n en la concha ac\u00fastica del parque Sagrado Coraz\u00f3n de Los Gaiteros de Pueblo Santo y Lina Babilonia y Son Ancestro. Todo esto siguiendo todas las normas de bioseguridad y recomendaciones que nos han dado desde la Secretar\u00eda de Salud y de Desarrollo Econ\u00f3mico\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Recomend\u00f3 que las personas que quieran asistir a estos eventos culturales deben llegar con mucho tiempo de anticipaci\u00f3n, \u201cporque vamos a tener un control de aforo. Vamos a tener el 25% del total del aforo del lugar y es lo que est\u00e1 permitido hasta este momento\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La secretaria de Cultura del distrito agreg\u00f3 que \u201cadem\u00e1s, tendremos se\u00f1alizaciones para que las personas guarden una distancia de por lo menos un metro entre ellos. El uso del tapabocas es absolutamente obligatorio; dispondremos de unos lugares para el lavado de manos de los asistentes. Esto por recomendaciones del Ministerio de Salud. La idea es que lleguen temprano y puedan entrar porque cuando se cumpla el aforo ya no habr\u00e1 m\u00e1s ingreso\u201d.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u201cEn la actividad que tenemos en la concha ac\u00fastica del parque Sagrado Coraz\u00f3n, hemos dispuesto que sea transmitida a trav\u00e9s de Facebook Live de la plataforma de la Alcald\u00eda de Barranquilla y de la Secretar\u00eda de Cultura y Patrimonio. As\u00ed que las personas que no puedan llegar por alguna circunstancia o que se haya completado el aforo, pueden conectarse y poder disfrutar de estos dos conciertos, que tendr\u00e1n una duraci\u00f3n aproximada de dos horas\u201d, termin\u00f3 diciendo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habr\u00e1 un concierto con Los Gaiteros de Pueblo Santo y Lina Babilonia. La secretaria de Cultura del Distrito, Mar\u00eda Teresa Fern\u00e1ndez, inform\u00f3 este viernes que est\u00e1 definida la programaci\u00f3n art\u00edstica y cultural que se desarrollar\u00e1 este fin de semana en cinco parques ya determinados, ubicados en las cinco localidades de Barranquilla. \u201cEstamos muy contentos porque&#8230;<\/p>\n","protected":false},"author":1,"featured_media":157448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60,88,89,56],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2021\/06\/Artes-escenicas.jpg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/157447"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=157447"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/157447\/revisions"}],"predecessor-version":[{"id":157449,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/157447\/revisions\/157449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/157448"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=157447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=157447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=157447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}