{"id":102752,"date":"2020-04-30T20:04:29","date_gmt":"2020-04-30T20:04:29","guid":{"rendered":"http:\/\/malamboradio.com\/web\/?p=102752"},"modified":"2020-04-30T20:04:33","modified_gmt":"2020-04-30T20:04:33","slug":"alcaldia-de-soledad-demarco-zonas-bancarias-para-evitar-aglomeraciones","status":"publish","type":"post","link":"https:\/\/malamboradio.com\/web\/2020\/04\/30\/alcaldia-de-soledad-demarco-zonas-bancarias-para-evitar-aglomeraciones\/","title":{"rendered":"Alcald\u00eda de Soledad  demarc\u00f3 zonas bancarias para evitar aglomeraciones"},"content":{"rendered":"\n<p>Soledad, 30 de abril de 2020.  Bajo el lema \u2018Ub\u00edcate en la l\u00ednea de la vida\u2019, la Alcald\u00eda de Soledad, a trav\u00e9s de la Oficina de Salud P\u00fablica, demarc\u00f3 las zonas bancarias del municipio con la intenci\u00f3n de que las personas guarden el metro de distancia establecido para evitar el contagio de Covid-19. <\/p>\n\n\n\n<p>Los sitios de espera de los bancos Popular, Davivienda y AV Villas fueron los primeros en ser se\u00f1alizados, teniendo en cuenta la alta afluencia de p\u00fablico. De igual forma, se instalaron avisos sobre el uso obligatorio de tapabocas y guantes. <\/p>\n\n\n\n<p>\u201cLa finalidad de esta medida es concientizar a los solede\u00f1os sobre los cuidados que hay que emplear cuando estamos fuera de nuestros hogares. Debemos ser responsables y evitar m\u00e1s casos de Covid-19 en nuestro municipio. Seremos muy severos con quienes incumplan con lo establecido\u201d, se\u00f1al\u00f3 el alcalde Rodolfo Ucr\u00f3s Rosales. <\/p>\n\n\n\n<p>Por su parte, el jefe de la Oficina de Salud P\u00fablica Municipal, Alvin Mart\u00ednez, explic\u00f3 que tambi\u00e9n se van a se\u00f1alizar los diferentes puntos donde se hacen entrega de los subsidios del Gobierno nacional a los ciudadanos. <\/p>\n\n\n\n<p>\u201cEs muy bueno que esta demarcaci\u00f3n se haya hecho y que lo sigan haciendo. Las personas no acatan las medidas si no se las imponen. Hay que estar vigilando con los cumplimiento y as\u00ed evitar contagiarnos\u201d, dijo Ana Robles, habitante del municipio.  <\/p>\n\n\n\n<p>Este jueves 30 de abril, el equipo de Salud P\u00fablica y el personal del Hospital Materno Infantil contin\u00faan realizando la labor de se\u00f1alizaci\u00f3n, y llevando el mensaje a todos los solede\u00f1os para que se ubiquen en la l\u00ednea de la vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soledad, 30 de abril de 2020. Bajo el lema \u2018Ub\u00edcate en la l\u00ednea de la vida\u2019, la Alcald\u00eda de Soledad, a trav\u00e9s de la Oficina de Salud P\u00fablica, demarc\u00f3 las zonas bancarias del municipio con la intenci\u00f3n de que las personas guarden el metro de distancia establecido para evitar el contagio de Covid-19. Los sitios&#8230;<\/p>\n","protected":false},"author":1,"featured_media":102753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/malamboradio.com\/web\/wp-content\/uploads\/2020\/04\/WhatsApp-Image-2020-04-30-at-3.03.31-PM.jpeg","_links":{"self":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/102752"}],"collection":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/comments?post=102752"}],"version-history":[{"count":1,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/102752\/revisions"}],"predecessor-version":[{"id":102756,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/posts\/102752\/revisions\/102756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media\/102753"}],"wp:attachment":[{"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/media?parent=102752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/categories?post=102752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malamboradio.com\/web\/wp-json\/wp\/v2\/tags?post=102752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}